﻿{"id":31932,"date":"2016-12-16T19:55:00","date_gmt":"2016-12-16T19:55:00","guid":{"rendered":"https:\/\/marcolift.com\/product\/palletpal-360\/"},"modified":"2024-05-12T13:07:33","modified_gmt":"2024-05-12T13:07:33","slug":"palletpal360","status":"publish","type":"product","link":"https:\/\/marcolift.com\/de\/produkt\/palletpal360\/","title":{"rendered":"PalletPal 360"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":29222,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1407],"product_tag":[],"class_list":{"0":"post-31932","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-palletpal-de","7":"pa_capacity-2040-de","8":"pa_lyftrorelse-711-de","9":"pa_netweight-186-de","10":"pa_ownheight-241-de","11":"pa_platformheight-1108-de","12":"pa_platformwidth-1108-de","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PalletPal 360 - Marco AB - Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcolift.com\/de\/produkt\/palletpal360\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PalletPal 360 - Marco AB - Deutschland\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcolift.com\/de\/produkt\/palletpal360\/\" \/>\n<meta property=\"og:site_name\" content=\"Marco AB\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-12T13:07:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcolift.com\/wp-content\/uploads\/2018\/11\/10_Pallet_Pal_360.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PalletPal 360 - Marco AB - Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcolift.com\/de\/produkt\/palletpal360\/","og_locale":"de_DE","og_type":"article","og_title":"PalletPal 360 - Marco AB - Deutschland","og_url":"https:\/\/marcolift.com\/de\/produkt\/palletpal360\/","og_site_name":"Marco AB","article_modified_time":"2024-05-12T13:07:33+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/marcolift.com\/wp-content\/uploads\/2018\/11\/10_Pallet_Pal_360.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/marcolift.com\/de\/produkt\/palletpal360\/","url":"https:\/\/marcolift.com\/de\/produkt\/palletpal360\/","name":"PalletPal 360 - Marco AB - Deutschland","isPartOf":{"@id":"https:\/\/marcolift.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcolift.com\/de\/produkt\/palletpal360\/#primaryimage"},"image":{"@id":"https:\/\/marcolift.com\/de\/produkt\/palletpal360\/#primaryimage"},"thumbnailUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2018\/11\/10_Pallet_Pal_360.jpg","datePublished":"2016-12-16T19:55:00+00:00","dateModified":"2024-05-12T13:07:33+00:00","breadcrumb":{"@id":"https:\/\/marcolift.com\/de\/produkt\/palletpal360\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcolift.com\/de\/produkt\/palletpal360\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/marcolift.com\/de\/produkt\/palletpal360\/#primaryimage","url":"https:\/\/marcolift.com\/wp-content\/uploads\/2018\/11\/10_Pallet_Pal_360.jpg","contentUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2018\/11\/10_Pallet_Pal_360.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/marcolift.com\/de\/produkt\/palletpal360\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcolift.com\/de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/marcolift.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"PalletPal 360"}]},{"@type":"WebSite","@id":"https:\/\/marcolift.com\/de\/#website","url":"https:\/\/marcolift.com\/de\/","name":"Marco AB","description":"","publisher":{"@id":"https:\/\/marcolift.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcolift.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/marcolift.com\/de\/#organization","name":"Marco AB","url":"https:\/\/marcolift.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/marcolift.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/02\/marco.jpg","contentUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/02\/marco.jpg","width":400,"height":400,"caption":"Marco AB"},"image":{"@id":"https:\/\/marcolift.com\/de\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/marcolift.com\/de\/wp-json\/wp\/v2\/product\/31932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcolift.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/marcolift.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcolift.com\/de\/wp-json\/wp\/v2\/media\/29222"}],"wp:attachment":[{"href":"https:\/\/marcolift.com\/de\/wp-json\/wp\/v2\/media?parent=31932"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/marcolift.com\/de\/wp-json\/wp\/v2\/product_brand?post=31932"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/marcolift.com\/de\/wp-json\/wp\/v2\/product_cat?post=31932"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/marcolift.com\/de\/wp-json\/wp\/v2\/product_tag?post=31932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}