﻿{"id":72676,"date":"2020-03-16T14:43:12","date_gmt":"2020-03-16T14:43:12","guid":{"rendered":"https:\/\/marcolift.com\/mercancias-entrantes-actualizacion-de-informacion\/"},"modified":"2020-03-16T14:43:12","modified_gmt":"2020-03-16T14:43:12","slug":"mercancias-entrantes-actualizacion-de-informacion","status":"publish","type":"post","link":"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/","title":{"rendered":"Mercanc\u00edas entrantes, actualizaci\u00f3n de informaci\u00f3n"},"content":{"rendered":"<h3><strong>Estimado cliente,<\/strong><\/h3>\n<p>Ya estamos viendo el impacto de la pandemia de coronavirus entre nuestros clientes. Algunos tienen dificultades para gestionar las entregas de sus mercanc\u00edas entrantes.<br \/>\n Queremos brindarle el mejor apoyo posible durante estos momentos dif\u00edciles. Por ello, hemos organizado diversos colaboradores locales para brindarle la ayuda que necesita con nuestras entregas.  <\/p>\n<p>Si se enfrenta a este tipo de problema con la recepci\u00f3n de mercanc\u00edas, p\u00f3ngase en contacto con nuestro servicio de atenci\u00f3n al cliente. Nosotros y nuestros socios haremos todo lo posible para garantizar que nuestros env\u00edos se realicen de forma r\u00e1pida y sin problemas. <\/p>\n<p>Atentamente,<br \/>\n Mi Hoffmann<br \/>\n Gerente de Atenci\u00f3n al Cliente<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimado cliente, Ya estamos viendo el impacto de la pandemia de coronavirus entre nuestros clientes. Algunos tienen dificultades para gestionar las entregas de sus mercanc\u00edas entrantes. Queremos brindarle el mejor apoyo posible durante estos momentos dif\u00edciles. Por ello, hemos organizado diversos colaboradores locales para brindarle la ayuda que necesita con nuestras entregas. Si se enfrenta [&#8230;]\n","protected":false},"author":11,"featured_media":72678,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2134],"tags":[],"class_list":["post-72676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercanc\u00edas entrantes, actualizaci\u00f3n de informaci\u00f3n - Marco AB<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercanc\u00edas entrantes, actualizaci\u00f3n de informaci\u00f3n - Marco AB\" \/>\n<meta property=\"og:description\" content=\"Estimado cliente, Ya estamos viendo el impacto de la pandemia de coronavirus entre nuestros clientes. Algunos tienen dificultades para gestionar las entregas de sus mercanc\u00edas entrantes. Queremos brindarle el mejor apoyo posible durante estos momentos dif\u00edciles. Por ello, hemos organizado diversos colaboradores locales para brindarle la ayuda que necesita con nuestras entregas. Si se enfrenta [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Marco AB\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-16T14:43:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcolift.com\/wp-content\/uploads\/2020\/03\/corona-22-mh.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"711\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"seutsi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"seutsi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercanc\u00edas entrantes, actualizaci\u00f3n de informaci\u00f3n - Marco AB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/","og_locale":"es_ES","og_type":"article","og_title":"Mercanc\u00edas entrantes, actualizaci\u00f3n de informaci\u00f3n - Marco AB","og_description":"Estimado cliente, Ya estamos viendo el impacto de la pandemia de coronavirus entre nuestros clientes. Algunos tienen dificultades para gestionar las entregas de sus mercanc\u00edas entrantes. Queremos brindarle el mejor apoyo posible durante estos momentos dif\u00edciles. Por ello, hemos organizado diversos colaboradores locales para brindarle la ayuda que necesita con nuestras entregas. Si se enfrenta [...]","og_url":"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/","og_site_name":"Marco AB","article_published_time":"2020-03-16T14:43:12+00:00","og_image":[{"width":1400,"height":711,"url":"https:\/\/marcolift.com\/wp-content\/uploads\/2020\/03\/corona-22-mh.jpg","type":"image\/jpeg"}],"author":"seutsi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"seutsi","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/#article","isPartOf":{"@id":"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/"},"author":{"name":"seutsi","@id":"https:\/\/marcolift.com\/es\/#\/schema\/person\/4bde815682f0968385265c292f1c9c85"},"headline":"Mercanc\u00edas entrantes, actualizaci\u00f3n de informaci\u00f3n","datePublished":"2020-03-16T14:43:12+00:00","mainEntityOfPage":{"@id":"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/"},"wordCount":121,"publisher":{"@id":"https:\/\/marcolift.com\/es\/#organization"},"image":{"@id":"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/#primaryimage"},"thumbnailUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2020\/03\/corona-22-mh.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/","url":"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/","name":"Mercanc\u00edas entrantes, actualizaci\u00f3n de informaci\u00f3n - Marco AB","isPartOf":{"@id":"https:\/\/marcolift.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/#primaryimage"},"image":{"@id":"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/#primaryimage"},"thumbnailUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2020\/03\/corona-22-mh.jpg","datePublished":"2020-03-16T14:43:12+00:00","breadcrumb":{"@id":"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/#primaryimage","url":"https:\/\/marcolift.com\/wp-content\/uploads\/2020\/03\/corona-22-mh.jpg","contentUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2020\/03\/corona-22-mh.jpg","width":1400,"height":711},{"@type":"BreadcrumbList","@id":"https:\/\/marcolift.com\/es\/mercancias-entrantes-actualizacion-de-informacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcolift.com\/es\/"},{"@type":"ListItem","position":2,"name":"Sin categor\u00eda","item":"https:\/\/marcolift.com\/es\/category\/sin-categoria\/"},{"@type":"ListItem","position":3,"name":"Mercanc\u00edas entrantes, actualizaci\u00f3n de informaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/marcolift.com\/es\/#website","url":"https:\/\/marcolift.com\/es\/","name":"Marco AB","description":"","publisher":{"@id":"https:\/\/marcolift.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcolift.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/marcolift.com\/es\/#organization","name":"Marco AB","url":"https:\/\/marcolift.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/marcolift.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/02\/marco.jpg","contentUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/02\/marco.jpg","width":400,"height":400,"caption":"Marco AB"},"image":{"@id":"https:\/\/marcolift.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/marcolift.com\/es\/#\/schema\/person\/4bde815682f0968385265c292f1c9c85","name":"seutsi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/25063bade91b7a7cf32eec6b6893af841214eda9f52a6cccc60a20bb92cb0878?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/25063bade91b7a7cf32eec6b6893af841214eda9f52a6cccc60a20bb92cb0878?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/25063bade91b7a7cf32eec6b6893af841214eda9f52a6cccc60a20bb92cb0878?s=96&d=mm&r=g","caption":"seutsi"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:00:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/posts\/72676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/comments?post=72676"}],"version-history":[{"count":0,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/posts\/72676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/media\/72678"}],"wp:attachment":[{"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/media?parent=72676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/categories?post=72676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/tags?post=72676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}