﻿{"id":73672,"date":"2022-05-03T10:42:37","date_gmt":"2022-05-03T10:42:37","guid":{"rendered":"https:\/\/marcolift.com\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/"},"modified":"2022-05-03T10:42:37","modified_gmt":"2022-05-03T10:42:37","slug":"la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad","status":"publish","type":"post","link":"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/","title":{"rendered":"La innovadora soluci\u00f3n AGV de CPM &#8211; Grupo D\u00fcrr aumenta la ergonom\u00eda y la flexibilidad"},"content":{"rendered":"<blockquote><p>La industria de fabricaci\u00f3n de autom\u00f3viles ha experimentado muchos cambios de paradigma a lo largo de los a\u00f1os. La globalizaci\u00f3n, las nuevas tecnolog\u00edas, las tendencias y la diversificaci\u00f3n han generado muchos retos, pero tambi\u00e9n oportunidades. No deber\u00eda sorprendernos que los fabricantes de autom\u00f3viles se tomen estos retos muy en serio y busquen siempre formas de innovar su negocio.  <\/p><\/blockquote>\n<figure id=\"attachment_43131\" aria-describedby=\"caption-attachment-43131\" style=\"width: 730px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/05\/Enrico-Maccarini-with-the-new-AGV-solution.jpg\" alt=\"Enrico Maccarini con la nueva soluci\u00f3n AGV\" width=\"730\" height=\"370\" class=\"size-full wp-image-43131\" srcset=\"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/05\/Enrico-Maccarini-with-the-new-AGV-solution.jpg 730w, https:\/\/marcolift.com\/wp-content\/uploads\/2022\/05\/Enrico-Maccarini-with-the-new-AGV-solution-340x172.jpg 340w, https:\/\/marcolift.com\/wp-content\/uploads\/2022\/05\/Enrico-Maccarini-with-the-new-AGV-solution-510x258.jpg 510w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><figcaption id=\"caption-attachment-43131\" class=\"wp-caption-text\">Enrico Maccarini (CPM &#8211; Grupo D\u00fcrr) con el nuevo AGV ProFleet 4200 de D\u00fcrr<\/figcaption><\/figure>\n<p>Uno de esos proyectos de innovaci\u00f3n se produjo cuando uno de los fabricantes de autom\u00f3viles m\u00e1s famosos se propuso recientemente mejorar a\u00fan m\u00e1s la ergonom\u00eda de sus trabajadores y aumentar la flexibilidad de una de sus l\u00edneas de producci\u00f3n. El proyecto culmin\u00f3 con una soluci\u00f3n de elevaci\u00f3n AGV personalizada con visi\u00f3n de futuro que incluye mesas elevadoras de VPG. <\/p>\n<p>En su nuevo emplazamiento, pronto dispondr\u00e1n de un <em>ProFleet 4200<\/em>, una soluci\u00f3n de elevaci\u00f3n AGV del Grupo CPM D\u00fcrr a la altura de la impresionante ingenier\u00eda de su \u00faltima marca de coches de lujo. El proyecto es un esfuerzo conjunto de CPM, VPG y el fabricante de coches. <\/p>\n<p>CPM, que forma parte del gigante mundial D\u00fcrr, est\u00e1 especializada en el montaje final y cuenta con una impresionante lista de clientes como Tesla y Ford. El grupo es l\u00edder del mercado mundial en el sector de la automoci\u00f3n, con unas ventas anuales de aproximadamente 4.000 millones de euros al a\u00f1o. <\/p>\n<p>Adem\u00e1s, la nueva soluci\u00f3n AGV de la f\u00e1brica puede muy bien ofrecer una visi\u00f3n del futuro. Hemos hablado con Enrico Maccarini, jefe de proyecto de CPM, para saber m\u00e1s. <\/p>\n<p>\u201cTuvimos que considerar una multitud de factores y asegurarnos de que el equipo pod\u00eda ofrecer los resultados deseados\u201d, empieza Enrico. \u201cDecidimos integrar <em>ProFleet<\/em> y la mesa elevadora para poder ajustar f\u00e1cilmente la posici\u00f3n y la altura para una acci\u00f3n espec\u00edfica. Tambi\u00e9n quer\u00edamos una soluci\u00f3n flexible para crear m\u00e1s oportunidades de fabricaci\u00f3n y posibles aplicaciones\u201d, contin\u00faa Enrico.  <\/p>\n<p>Su funcionamiento es bastante ingenioso. La carrocer\u00eda del coche se eleva desde el techo y el AGV se coloca debajo. A continuaci\u00f3n, la pieza se eleva con cuidado hasta su posici\u00f3n mediante la mesa elevadora mientras se baja la carrocer\u00eda. Cuando las piezas se encuentran en la posici\u00f3n correcta, el trabajador puede inspeccionar, montar y fijar f\u00e1cilmente la pieza donde corresponde. Y luego, a la siguiente estaci\u00f3n para la siguiente pieza o acci\u00f3n.    <\/p>\n<figure id=\"attachment_43149\" aria-describedby=\"caption-attachment-43149\" style=\"width: 350px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/05\/Joakim-Paulsson-R-and-Rasmus-LundinL-at-VPG-site.png\" alt=\"\" width=\"350\" height=\"397\" class=\"size-full wp-image-43149\" srcset=\"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/05\/Joakim-Paulsson-R-and-Rasmus-LundinL-at-VPG-site.png 350w, https:\/\/marcolift.com\/wp-content\/uploads\/2022\/05\/Joakim-Paulsson-R-and-Rasmus-LundinL-at-VPG-site-340x386.png 340w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><figcaption id=\"caption-attachment-43149\" class=\"wp-caption-text\">Joakim Paulsson (dcha.) y Rasmus Lundin (izq.) en las instalaciones de VPG<\/figcaption><\/figure>\n<p>\u201cLa soluci\u00f3n AGV final utilizar\u00e1 un elevador mec\u00e1nico en espiral en lugar de uno hidr\u00e1ulico para conseguir un nivel extra de precisi\u00f3n y reducir el uso de aceite\u201d, dice Joakim Paulsson, de VPG.<\/p>\n<p>\u201cNuestro objetivo es siempre satisfacer las necesidades del cliente y, si eso significa que debemos pensar de forma diferente para conseguir los resultados deseados, eso es lo que haremos. Utilizar un elevador en espiral es un buen complemento para determinadas operaciones y l\u00edneas de producci\u00f3n\u201d, a\u00f1ade Joakim.<\/p>\n<p>Sospechamos que este tipo de soluci\u00f3n de elevaci\u00f3n AGV ser\u00e1 cada vez m\u00e1s habitual en el futuro. Con los recientes avances en tecnolog\u00eda e IA, s\u00f3lo hemos empezado a ara\u00f1ar la superficie de lo que es posible. La idea de una \u201cf\u00e1brica l\u00edquida\u201d en la que varios AGV tengan plena movilidad y puedan utilizarse para una gran variedad de tareas es definitivamente intrigante.  <\/p>\n<p>\u201cHa habido muchos retos en el camino, pero lo hemos conseguido. VPG ha sido un apoyo fant\u00e1stico en todo esto. El resultado final es estupendo y estamos impacientes por entregarlo todo en la obra\u201d, concluye Enrico.<\/p>\n<p><a href=\"https:\/\/www.durr.com\/en\/company\/locations\/duerr-italy\/cpm-spa\" rel=\"noopener\" target=\"_blank\"><u>CPM &#8211; Grupo D\u00fcrr<\/u><\/a><\/p>\n<p><a href=\"https:\/\/marcolift.com\/application\/agv\/\"><u>Aplicaciones AGV<\/u><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La industria de fabricaci\u00f3n de autom\u00f3viles ha experimentado muchos cambios de paradigma a lo largo de los a\u00f1os. La globalizaci\u00f3n, las nuevas tecnolog\u00edas, las tendencias y la diversificaci\u00f3n han generado muchos retos, pero tambi\u00e9n oportunidades. No deber\u00eda sorprendernos que los fabricantes de autom\u00f3viles se tomen estos retos muy en serio y busquen siempre formas de [&#8230;]\n","protected":false},"author":11,"featured_media":73685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2138],"tags":[],"class_list":["post-73672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aplicaciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La innovadora soluci\u00f3n AGV de CPM - Grupo D\u00fcrr aumenta la ergonom\u00eda y la flexibilidad - Marco AB<\/title>\n<meta name=\"description\" content=\"La industria de fabricaci\u00f3n de autom\u00f3viles ha pasado por muchos cambios de paradigma a lo largo de los a\u00f1os. La globalizaci\u00f3n, las nuevas tecnolog\u00edas, las tendencias\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La innovadora soluci\u00f3n AGV de CPM - Grupo D\u00fcrr aumenta la ergonom\u00eda y la flexibilidad - Marco AB\" \/>\n<meta property=\"og:description\" content=\"La industria de fabricaci\u00f3n de autom\u00f3viles ha pasado por muchos cambios de paradigma a lo largo de los a\u00f1os. La globalizaci\u00f3n, las nuevas tecnolog\u00edas, las tendencias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Marco AB\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-03T10:42:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/05\/agv-nl2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"992\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"seutsi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"seutsi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La innovadora soluci\u00f3n AGV de CPM - Grupo D\u00fcrr aumenta la ergonom\u00eda y la flexibilidad - Marco AB","description":"La industria de fabricaci\u00f3n de autom\u00f3viles ha pasado por muchos cambios de paradigma a lo largo de los a\u00f1os. La globalizaci\u00f3n, las nuevas tecnolog\u00edas, las tendencias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/","og_locale":"es_ES","og_type":"article","og_title":"La innovadora soluci\u00f3n AGV de CPM - Grupo D\u00fcrr aumenta la ergonom\u00eda y la flexibilidad - Marco AB","og_description":"La industria de fabricaci\u00f3n de autom\u00f3viles ha pasado por muchos cambios de paradigma a lo largo de los a\u00f1os. La globalizaci\u00f3n, las nuevas tecnolog\u00edas, las tendencias","og_url":"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/","og_site_name":"Marco AB","article_published_time":"2022-05-03T10:42:37+00:00","og_image":[{"width":1600,"height":992,"url":"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/05\/agv-nl2.jpg","type":"image\/jpeg"}],"author":"seutsi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"seutsi","Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/#article","isPartOf":{"@id":"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/"},"author":{"name":"seutsi","@id":"https:\/\/marcolift.com\/es\/#\/schema\/person\/4bde815682f0968385265c292f1c9c85"},"headline":"La innovadora soluci\u00f3n AGV de CPM &#8211; Grupo D\u00fcrr aumenta la ergonom\u00eda y la flexibilidad","datePublished":"2022-05-03T10:42:37+00:00","mainEntityOfPage":{"@id":"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/"},"wordCount":686,"publisher":{"@id":"https:\/\/marcolift.com\/es\/#organization"},"image":{"@id":"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/#primaryimage"},"thumbnailUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/05\/agv-nl2.jpg","articleSection":["Aplicaciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/","url":"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/","name":"La innovadora soluci\u00f3n AGV de CPM - Grupo D\u00fcrr aumenta la ergonom\u00eda y la flexibilidad - Marco AB","isPartOf":{"@id":"https:\/\/marcolift.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/#primaryimage"},"image":{"@id":"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/#primaryimage"},"thumbnailUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/05\/agv-nl2.jpg","datePublished":"2022-05-03T10:42:37+00:00","description":"La industria de fabricaci\u00f3n de autom\u00f3viles ha pasado por muchos cambios de paradigma a lo largo de los a\u00f1os. La globalizaci\u00f3n, las nuevas tecnolog\u00edas, las tendencias","breadcrumb":{"@id":"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/#primaryimage","url":"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/05\/agv-nl2.jpg","contentUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/05\/agv-nl2.jpg","width":1600,"height":992},{"@type":"BreadcrumbList","@id":"https:\/\/marcolift.com\/es\/la-innovadora-solucion-agv-de-cpm-grupo-durr-aumenta-la-ergonomia-y-la-flexibilidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcolift.com\/es\/"},{"@type":"ListItem","position":2,"name":"Aplicaciones","item":"https:\/\/marcolift.com\/es\/category\/aplicaciones\/"},{"@type":"ListItem","position":3,"name":"La innovadora soluci\u00f3n AGV de CPM &#8211; Grupo D\u00fcrr aumenta la ergonom\u00eda y la flexibilidad"}]},{"@type":"WebSite","@id":"https:\/\/marcolift.com\/es\/#website","url":"https:\/\/marcolift.com\/es\/","name":"Marco AB","description":"","publisher":{"@id":"https:\/\/marcolift.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcolift.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/marcolift.com\/es\/#organization","name":"Marco AB","url":"https:\/\/marcolift.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/marcolift.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/02\/marco.jpg","contentUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/02\/marco.jpg","width":400,"height":400,"caption":"Marco AB"},"image":{"@id":"https:\/\/marcolift.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/marcolift.com\/es\/#\/schema\/person\/4bde815682f0968385265c292f1c9c85","name":"seutsi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/25063bade91b7a7cf32eec6b6893af841214eda9f52a6cccc60a20bb92cb0878?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/25063bade91b7a7cf32eec6b6893af841214eda9f52a6cccc60a20bb92cb0878?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/25063bade91b7a7cf32eec6b6893af841214eda9f52a6cccc60a20bb92cb0878?s=96&d=mm&r=g","caption":"seutsi"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 00:12:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/posts\/73672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/comments?post=73672"}],"version-history":[{"count":0,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/posts\/73672\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/media\/73685"}],"wp:attachment":[{"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/media?parent=73672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/categories?post=73672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/tags?post=73672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}