﻿{"id":73786,"date":"2021-09-01T09:42:33","date_gmt":"2021-09-01T09:42:33","guid":{"rendered":"https:\/\/marcolift.com\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/"},"modified":"2025-06-27T15:43:58","modified_gmt":"2025-06-27T15:43:58","slug":"en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas","status":"publish","type":"post","link":"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/","title":{"rendered":"En tu edificio pueden esconderse espacios de almacenamiento que ahorran costes: \u00a1no te los pierdas!"},"content":{"rendered":"<blockquote><p>La gesti\u00f3n de existencias siempre se ve sometida a presi\u00f3n con la llegada del oto\u00f1o. Los fabricantes aumentan la producci\u00f3n despu\u00e9s del verano, mientras que los compradores esperan entregas y rotaci\u00f3n r\u00e1pidas. El espacio de almacenamiento flexible es un bien escaso. Afortunadamente, existe una soluci\u00f3n eficaz y econ\u00f3mica.   <\/p><\/blockquote>\n<p><strong>Un recurso ignorado que se esconde a plena vista<\/strong><\/p>\n<p>Las empresas suelen recurrir a costosas instalaciones de almacenamiento de terceros, que complican su log\u00edstica. O se plantean proyectos largos y caros para construir nuevos almacenes. Pasan por alto un recurso del que suelen disponer en abundancia: el espacio vac\u00edo en entreplantas y bajo cubierta.  <\/p>\n<p>\u201cProbablemente, estas empresas han llegado a la conclusi\u00f3n de que, aunque podr\u00edan explotar estas zonas con montacargas, este tipo de equipos son caros y molestos de instalar y hacer funcionar\u201d, dice Andreas H\u00f6glund, Director de Proyectos. \u201cSin embargo, hay otra forma: el elevador accionado por m\u00e1stil, o MDL\u201d. <\/p>\n<figure id=\"attachment_40390\" aria-describedby=\"caption-attachment-40390\" style=\"width: 730px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-40390\" src=\"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/Andreas-Hoglund-Project-Manager.jpg\" alt=\"\" width=\"730\" height=\"548\" srcset=\"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/Andreas-Hoglund-Project-Manager.jpg 730w, https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/Andreas-Hoglund-Project-Manager-340x255.jpg 340w, https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/Andreas-Hoglund-Project-Manager-510x383.jpg 510w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><figcaption id=\"caption-attachment-40390\" class=\"wp-caption-text\">Andreas H\u00f6glund, Director de Proyectos<\/figcaption><\/figure>\n<p><strong>Abre nuevas oportunidades con MDL-I<\/strong><\/p>\n<p>Los elevadores de m\u00e1stil ya est\u00e1n disponibles para aplicaciones industriales, lo que abre nuevas oportunidades para aprovechar espacios de almacenamiento que de otro modo estar\u00edan fuera de nuestro alcance. \u201cNuestro propio MDL-I est\u00e1 orientado espec\u00edficamente al uso industrial\u201d, dice Andreas. \u201cSe centra en el movimiento de mercanc\u00edas, no de personas, por lo que obtener las autorizaciones necesarias es r\u00e1pido y sencillo. Y el dise\u00f1o estilizado que ahorra espacio permite disponer del mayor espacio posible para el almacenamiento\u201d.  <\/p>\n<p>La seguridad es importante, por supuesto. \u201cLa MDL-I cuenta con un completo conjunto de estanter\u00edas y carriles de protecci\u00f3n para mantener a salvo tanto a las personas como a las mercanc\u00edas durante las operaciones\u201d, se\u00f1ala Andreas. <\/p>\n<div id='gallery-1' class='gallery galleryid-73786 gallery-columns-2 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/Space-above-an-industrial-structure-suitable-for-storage.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"190\" src=\"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/Space-above-an-industrial-structure-suitable-for-storage-340x190.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Space above an industrial structure suitable for storage\" aria-describedby=\"gallery-1-73816\" srcset=\"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/Space-above-an-industrial-structure-suitable-for-storage-340x190.jpg 340w, https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/Space-above-an-industrial-structure-suitable-for-storage.jpg 454w\" sizes=\"auto, (max-width: 340px) 100vw, 340px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-73816'>\n\t\t\t\tSpace above an industrial structure suitable for storage\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/MDL-I-enables-full-use-of-overlooked-space.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"190\" src=\"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/MDL-I-enables-full-use-of-overlooked-space-340x190.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"MDL-I enables full use of overlooked space\" aria-describedby=\"gallery-1-73815\" srcset=\"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/MDL-I-enables-full-use-of-overlooked-space-340x190.jpg 340w, https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/MDL-I-enables-full-use-of-overlooked-space.jpg 454w\" sizes=\"auto, (max-width: 340px) 100vw, 340px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-73815'>\n\t\t\t\tMDL-I enables full use of overlooked space\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p><strong>Instalaci\u00f3n r\u00e1pida y econ\u00f3mica<\/strong><\/p>\n<p>\u201cEn esta \u00e9poca del a\u00f1o, hay una necesidad especial de soluciones que se puedan poner en marcha r\u00e1pidamente. Eso excluye claramente los montacargas tradicionales. En cambio, puedes instalar nuestros modelos MDL-I de dise\u00f1o inteligente en s\u00f3lo dos d\u00edas in situ\u201d, dice Andreas. \u201cNo es necesario hacer obras en el suelo ni otros preparativos costosos y que llevan mucho tiempo. Todo lo que necesitas es una peque\u00f1a superficie de suelo libre\u201d. <\/p>\n<figure id=\"attachment_40404\" aria-describedby=\"caption-attachment-40404\" style=\"width: 730px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-40404\" src=\"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/Patrik-Brandt-and-Marcus-Andersson-at-Toveks-with-their-safe-and-time-saving-MDL-I.jpg\" alt=\"Patrik Brandt y Marcus Andersson en Toveks con su MDL I seguro y que ahorra tiempo\" width=\"730\" height=\"510\" srcset=\"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/Patrik-Brandt-and-Marcus-Andersson-at-Toveks-with-their-safe-and-time-saving-MDL-I.jpg 730w, https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/Patrik-Brandt-and-Marcus-Andersson-at-Toveks-with-their-safe-and-time-saving-MDL-I-340x238.jpg 340w, https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/Patrik-Brandt-and-Marcus-Andersson-at-Toveks-with-their-safe-and-time-saving-MDL-I-510x356.jpg 510w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><figcaption id=\"caption-attachment-40404\" class=\"wp-caption-text\">Patrik Brandt y Marcus Andersson en Toveks con su MDL-I seguro y que ahorra tiempo<\/figcaption><\/figure>\n<p><strong>MDL-I en acci\u00f3n<\/strong><\/p>\n<p>Las tiendas de neum\u00e1ticos y los centros de servicio ofrecen un buen ejemplo de MDL-I en la pr\u00e1ctica. Seg\u00fan Andreas, ya se est\u00e1 convirtiendo en una soluci\u00f3n est\u00e1ndar en este tipo de establecimientos. \u201cA medida que los conductores se preparan para el invierno, es imprescindible disponer de espacio para almacenar neum\u00e1ticos con acceso r\u00e1pido y f\u00e1cil. Se intercambian y almacenan neum\u00e1ticos de invierno y verano, y los clientes exigen rapidez y bajos costes. Es una de las aplicaciones perfectas para nuestro MDL-I\u201d.  <\/p>\n<p>La gama MDL-I ofrece actualmente dos modelos para cargas de hasta 1500 kg: el MDL-I 350 y el MDL-I 550, con alturas m\u00e1ximas de elevaci\u00f3n de 3,5 y 5,5 metros respectivamente.<\/p>\n<p>Sigue leyendo:<\/p>\n<ul>\n<li><a href=\"https:\/\/marcolift.com\/es\/ahorro-considerable-con-la-nueva-mdl\/\"><u>Conseguir un gran ahorro de costes a lo largo de la vida<\/u><\/a> con el MDL-I<\/li>\n<li>Caso pr\u00e1ctico: <a href=\"https:\/\/marcolift.com\/es\/aliviar-la-presion-sobre-los-concesionarios-de-automoviles\/\"><u>Crear un almacenamiento econ\u00f3mico y flexible<\/u><\/a> en el sector del autom\u00f3vil con MDL-I.<\/li>\n<\/ul>\n<a href=\"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/MDL350-550_Marco_GB.pdf\" target=\"_blank\" class=\"button secondary is-secondary is-medium\" rel=\"noopener\" >\n\t\t<span>Hoja de Producto (2,45mb, .pdf)<\/span>\n\t<\/a>\n\n","protected":false},"excerpt":{"rendered":"<p>La gesti\u00f3n de existencias siempre se ve sometida a presi\u00f3n con la llegada del oto\u00f1o. Los fabricantes aumentan la producci\u00f3n despu\u00e9s del verano, mientras que los compradores esperan entregas y rotaci\u00f3n r\u00e1pidas. El espacio de almacenamiento flexible es un bien escaso. Afortunadamente, existe una soluci\u00f3n eficaz y econ\u00f3mica. Un recurso ignorado que se esconde a [&#8230;]\n","protected":false},"author":11,"featured_media":73812,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2138],"tags":[],"class_list":["post-73786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aplicaciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En tu edificio pueden esconderse espacios de almacenamiento que ahorran costes: \u00a1no te los pierdas! - Marco AB<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En tu edificio pueden esconderse espacios de almacenamiento que ahorran costes: \u00a1no te los pierdas! - Marco AB\" \/>\n<meta property=\"og:description\" content=\"La gesti\u00f3n de existencias siempre se ve sometida a presi\u00f3n con la llegada del oto\u00f1o. Los fabricantes aumentan la producci\u00f3n despu\u00e9s del verano, mientras que los compradores esperan entregas y rotaci\u00f3n r\u00e1pidas. El espacio de almacenamiento flexible es un bien escaso. Afortunadamente, existe una soluci\u00f3n eficaz y econ\u00f3mica. Un recurso ignorado que se esconde a [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/\" \/>\n<meta property=\"og:site_name\" content=\"Marco AB\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-01T09:42:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-27T15:43:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/HEADER-Storage-M-H.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"763\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"seutsi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"seutsi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En tu edificio pueden esconderse espacios de almacenamiento que ahorran costes: \u00a1no te los pierdas! - Marco AB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/","og_locale":"es_ES","og_type":"article","og_title":"En tu edificio pueden esconderse espacios de almacenamiento que ahorran costes: \u00a1no te los pierdas! - Marco AB","og_description":"La gesti\u00f3n de existencias siempre se ve sometida a presi\u00f3n con la llegada del oto\u00f1o. Los fabricantes aumentan la producci\u00f3n despu\u00e9s del verano, mientras que los compradores esperan entregas y rotaci\u00f3n r\u00e1pidas. El espacio de almacenamiento flexible es un bien escaso. Afortunadamente, existe una soluci\u00f3n eficaz y econ\u00f3mica. Un recurso ignorado que se esconde a [...]","og_url":"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/","og_site_name":"Marco AB","article_published_time":"2021-09-01T09:42:33+00:00","article_modified_time":"2025-06-27T15:43:58+00:00","og_image":[{"width":1400,"height":763,"url":"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/HEADER-Storage-M-H.jpg","type":"image\/jpeg"}],"author":"seutsi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"seutsi","Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/#article","isPartOf":{"@id":"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/"},"author":{"name":"seutsi","@id":"https:\/\/marcolift.com\/es\/#\/schema\/person\/4bde815682f0968385265c292f1c9c85"},"headline":"En tu edificio pueden esconderse espacios de almacenamiento que ahorran costes: \u00a1no te los pierdas!","datePublished":"2021-09-01T09:42:33+00:00","dateModified":"2025-06-27T15:43:58+00:00","mainEntityOfPage":{"@id":"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/"},"wordCount":614,"publisher":{"@id":"https:\/\/marcolift.com\/es\/#organization"},"image":{"@id":"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/#primaryimage"},"thumbnailUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/HEADER-Storage-M-H.jpg","articleSection":["Aplicaciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/","url":"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/","name":"En tu edificio pueden esconderse espacios de almacenamiento que ahorran costes: \u00a1no te los pierdas! - Marco AB","isPartOf":{"@id":"https:\/\/marcolift.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/#primaryimage"},"image":{"@id":"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/#primaryimage"},"thumbnailUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/HEADER-Storage-M-H.jpg","datePublished":"2021-09-01T09:42:33+00:00","dateModified":"2025-06-27T15:43:58+00:00","breadcrumb":{"@id":"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/#primaryimage","url":"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/HEADER-Storage-M-H.jpg","contentUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2021\/09\/HEADER-Storage-M-H.jpg","width":1400,"height":763},{"@type":"BreadcrumbList","@id":"https:\/\/marcolift.com\/es\/en-tu-edificio-pueden-esconderse-espacios-de-almacenamiento-que-ahorran-costes-no-te-los-pierdas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcolift.com\/es\/"},{"@type":"ListItem","position":2,"name":"Newsletter","item":"https:\/\/marcolift.com\/category\/newsletter\/"},{"@type":"ListItem","position":3,"name":"Bolet\u00edn n\u00ba 8 - 2021","item":"https:\/\/marcolift.com\/es\/category\/boletin-no-8-2021\/"},{"@type":"ListItem","position":4,"name":"En tu edificio pueden esconderse espacios de almacenamiento que ahorran costes: \u00a1no te los pierdas!"}]},{"@type":"WebSite","@id":"https:\/\/marcolift.com\/es\/#website","url":"https:\/\/marcolift.com\/es\/","name":"Marco AB","description":"","publisher":{"@id":"https:\/\/marcolift.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcolift.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/marcolift.com\/es\/#organization","name":"Marco AB","url":"https:\/\/marcolift.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/marcolift.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/02\/marco.jpg","contentUrl":"https:\/\/marcolift.com\/wp-content\/uploads\/2022\/02\/marco.jpg","width":400,"height":400,"caption":"Marco AB"},"image":{"@id":"https:\/\/marcolift.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/marcolift.com\/es\/#\/schema\/person\/4bde815682f0968385265c292f1c9c85","name":"seutsi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/25063bade91b7a7cf32eec6b6893af841214eda9f52a6cccc60a20bb92cb0878?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/25063bade91b7a7cf32eec6b6893af841214eda9f52a6cccc60a20bb92cb0878?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/25063bade91b7a7cf32eec6b6893af841214eda9f52a6cccc60a20bb92cb0878?s=96&d=mm&r=g","caption":"seutsi"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:56:45","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/posts\/73786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/comments?post=73786"}],"version-history":[{"count":2,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/posts\/73786\/revisions"}],"predecessor-version":[{"id":73828,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/posts\/73786\/revisions\/73828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/media\/73812"}],"wp:attachment":[{"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/media?parent=73786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/categories?post=73786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcolift.com\/es\/wp-json\/wp\/v2\/tags?post=73786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}